{"id":7871,"date":"2023-09-27T14:23:27","date_gmt":"2023-09-27T08:53:27","guid":{"rendered":"https:\/\/staging.analyticachemie.in\/?post_type=product&#038;p=7871"},"modified":"2023-11-03T18:10:16","modified_gmt":"2023-11-03T12:40:16","slug":"paclitaxel-imp-o-ep","status":"publish","type":"product","link":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/","title":{"rendered":"Paclitaxel Imp.  O (EP)"},"content":{"rendered":"<p>ACI-162215 182946-93-6 Paclitaxel Imp.  O (EP) C49H53NO14 4,10?-bis(acetyloxy)-1,7?-dihydroxy-13?-[[(2R,3S)-2-hydroxy-3-phenyl-3-[[(2E)-3-phenylprop-2-enoyl]amino]propanoyl]oxy]-9-oxo-5?,20-epoxytax-11-en-2?-yl benzoate<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACI-162215 182946-93-6 Paclitaxel Imp. O (EP) C49H53NO14 4,10?-bis(acetyloxy)-1,7?-dihydroxy-13?-[[(2R,3S)-2-hydroxy-3-phenyl-3-[[(2E)-3-phenylprop-2-enoyl]amino]propanoyl]oxy]-9-oxo-5?,20-epoxytax-11-en-2?-yl benzoate<\/p>\n","protected":false},"featured_media":7872,"template":"","meta":{"inline_featured_image":false},"product_cat":[1394,16],"product_tag":[],"class_list":["post-7871","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-paclitaxel","product_cat-pharmaceutical-impurity-standards"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Paclitaxel Imp. O (EP) - Analytica Chemie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paclitaxel Imp. O (EP)\" \/>\n<meta property=\"og:description\" content=\"ACI-162215 182946-93-6 Paclitaxel Imp. O (EP) C49H53NO14 4,10?-bis(acetyloxy)-1,7?-dihydroxy-13?-[[(2R,3S)-2-hydroxy-3-phenyl-3-[[(2E)-3-phenylprop-2-enoyl]amino]propanoyl]oxy]-9-oxo-5?,20-epoxytax-11-en-2?-yl benzoate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/\" \/>\n<meta property=\"og:site_name\" content=\"Analytica Chemie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/analyticachemieinc\/yoast\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T12:40:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-162215-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"486\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/paclitaxel-imp-o-ep\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/paclitaxel-imp-o-ep\\\/\",\"name\":\"Paclitaxel Imp. O (EP) - Analytica Chemie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/paclitaxel-imp-o-ep\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/paclitaxel-imp-o-ep\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-162215-1.jpg\",\"datePublished\":\"2023-09-27T08:53:27+00:00\",\"dateModified\":\"2023-11-03T12:40:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/paclitaxel-imp-o-ep\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/paclitaxel-imp-o-ep\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/paclitaxel-imp-o-ep\\\/#primaryimage\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-162215-1.jpg\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-162215-1.jpg\",\"width\":486,\"height\":317},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/paclitaxel-imp-o-ep\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Paclitaxel Imp. O (EP)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#website\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\",\"name\":\"Analytica Chemie Inc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#organization\",\"name\":\"Analytica Chemie Inc\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"width\":3876,\"height\":1054,\"caption\":\"Analytica Chemie Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/analyticachemieinc\\\/yoast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/76600123\\\/admin\\\/dashboard\\\/yoast\",\"https:\\\/\\\/www.youtube.com\\\/@analyticachemieinc.6555\\\/yoast\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Paclitaxel Imp. O (EP) - Analytica Chemie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/","og_locale":"en_US","og_type":"article","og_title":"Paclitaxel Imp. O (EP)","og_description":"ACI-162215 182946-93-6 Paclitaxel Imp. O (EP) C49H53NO14 4,10?-bis(acetyloxy)-1,7?-dihydroxy-13?-[[(2R,3S)-2-hydroxy-3-phenyl-3-[[(2E)-3-phenylprop-2-enoyl]amino]propanoyl]oxy]-9-oxo-5?,20-epoxytax-11-en-2?-yl benzoate","og_url":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/","og_site_name":"Analytica Chemie","article_publisher":"https:\/\/www.facebook.com\/analyticachemieinc\/yoast","article_modified_time":"2023-11-03T12:40:16+00:00","og_image":[{"width":486,"height":317,"url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-162215-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/","url":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/","name":"Paclitaxel Imp. O (EP) - Analytica Chemie","isPartOf":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/#primaryimage"},"image":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/#primaryimage"},"thumbnailUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-162215-1.jpg","datePublished":"2023-09-27T08:53:27+00:00","dateModified":"2023-11-03T12:40:16+00:00","breadcrumb":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/#primaryimage","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-162215-1.jpg","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-162215-1.jpg","width":486,"height":317},{"@type":"BreadcrumbList","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/paclitaxel-imp-o-ep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analyticachemie.in\/ver-2\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/analyticachemie.in\/ver-2\/shop\/"},{"@type":"ListItem","position":3,"name":"Paclitaxel Imp. O (EP)"}]},{"@type":"WebSite","@id":"https:\/\/analyticachemie.in\/ver-2\/#website","url":"https:\/\/analyticachemie.in\/ver-2\/","name":"Analytica Chemie Inc","description":"","publisher":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analyticachemie.in\/ver-2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/analyticachemie.in\/ver-2\/#organization","name":"Analytica Chemie Inc","url":"https:\/\/analyticachemie.in\/ver-2\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/ver-2\/#\/schema\/logo\/image\/","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-Logo.png","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-Logo.png","width":3876,"height":1054,"caption":"Analytica Chemie Inc"},"image":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/analyticachemieinc\/yoast","https:\/\/www.linkedin.com\/company\/76600123\/admin\/dashboard\/yoast","https:\/\/www.youtube.com\/@analyticachemieinc.6555\/yoast"]}]}},"_links":{"self":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product\/7871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media\/7872"}],"wp:attachment":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media?parent=7871"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_cat?post=7871"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_tag?post=7871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}