{"id":6546,"date":"2023-09-27T14:15:02","date_gmt":"2023-09-27T08:45:02","guid":{"rendered":"https:\/\/staging.analyticachemie.in\/?post_type=product&#038;p=6546"},"modified":"2023-11-03T18:06:43","modified_gmt":"2023-11-03T12:36:43","slug":"l-ornithine-l-aspartate","status":"publish","type":"product","link":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/","title":{"rendered":"L-Ornithine L-Aspartate"},"content":{"rendered":"<p>ACI-151620 3230-94-2 L-Ornithine L-Aspartate C9H19N3O6 (S)-2,5-Diaminopentanoic acid L-aspartate salt<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACI-151620 3230-94-2 L-Ornithine L-Aspartate C9H19N3O6 (S)-2,5-Diaminopentanoic acid L-aspartate salt<\/p>\n","protected":false},"featured_media":6547,"template":"","meta":{"inline_featured_image":false},"product_cat":[88,18],"product_tag":[],"class_list":["post-6546","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-chemical-intermediate","product_cat-pharmaceutical-intermediates"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L-Ornithine L-Aspartate - Analytica Chemie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L-Ornithine L-Aspartate\" \/>\n<meta property=\"og:description\" content=\"ACI-151620 3230-94-2 L-Ornithine L-Aspartate C9H19N3O6 (S)-2,5-Diaminopentanoic acid L-aspartate salt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/\" \/>\n<meta property=\"og:site_name\" content=\"Analytica Chemie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/analyticachemieinc\/yoast\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T12:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-151620-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/l-ornithine-l-aspartate\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/l-ornithine-l-aspartate\\\/\",\"name\":\"L-Ornithine L-Aspartate - Analytica Chemie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/l-ornithine-l-aspartate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/l-ornithine-l-aspartate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-151620-1.jpg\",\"datePublished\":\"2023-09-27T08:45:02+00:00\",\"dateModified\":\"2023-11-03T12:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/l-ornithine-l-aspartate\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/l-ornithine-l-aspartate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/l-ornithine-l-aspartate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-151620-1.jpg\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-151620-1.jpg\",\"width\":400,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/l-ornithine-l-aspartate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L-Ornithine L-Aspartate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#website\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/\",\"name\":\"Analytica Chemie Inc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analyticachemie.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#organization\",\"name\":\"Analytica Chemie Inc\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"width\":3876,\"height\":1054,\"caption\":\"Analytica Chemie Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/analyticachemieinc\\\/yoast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/76600123\\\/admin\\\/dashboard\\\/yoast\",\"https:\\\/\\\/www.youtube.com\\\/@analyticachemieinc.6555\\\/yoast\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L-Ornithine L-Aspartate - Analytica Chemie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/","og_locale":"en_US","og_type":"article","og_title":"L-Ornithine L-Aspartate","og_description":"ACI-151620 3230-94-2 L-Ornithine L-Aspartate C9H19N3O6 (S)-2,5-Diaminopentanoic acid L-aspartate salt","og_url":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/","og_site_name":"Analytica Chemie","article_publisher":"https:\/\/www.facebook.com\/analyticachemieinc\/yoast","article_modified_time":"2023-11-03T12:36:43+00:00","og_image":[{"width":400,"height":183,"url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-151620-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/","url":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/","name":"L-Ornithine L-Aspartate - Analytica Chemie","isPartOf":{"@id":"https:\/\/analyticachemie.in\/#website"},"primaryImageOfPage":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/#primaryimage"},"image":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/#primaryimage"},"thumbnailUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-151620-1.jpg","datePublished":"2023-09-27T08:45:02+00:00","dateModified":"2023-11-03T12:36:43+00:00","breadcrumb":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/#primaryimage","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-151620-1.jpg","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-151620-1.jpg","width":400,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/l-ornithine-l-aspartate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analyticachemie.in\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/analyticachemie.in\/shop\/"},{"@type":"ListItem","position":3,"name":"L-Ornithine L-Aspartate"}]},{"@type":"WebSite","@id":"https:\/\/analyticachemie.in\/#website","url":"https:\/\/analyticachemie.in\/","name":"Analytica Chemie Inc","description":"","publisher":{"@id":"https:\/\/analyticachemie.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analyticachemie.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/analyticachemie.in\/#organization","name":"Analytica Chemie Inc","url":"https:\/\/analyticachemie.in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/#\/schema\/logo\/image\/","url":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-Logo.png","contentUrl":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-Logo.png","width":3876,"height":1054,"caption":"Analytica Chemie Inc"},"image":{"@id":"https:\/\/analyticachemie.in\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/analyticachemieinc\/yoast","https:\/\/www.linkedin.com\/company\/76600123\/admin\/dashboard\/yoast","https:\/\/www.youtube.com\/@analyticachemieinc.6555\/yoast"]}]}},"_links":{"self":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product\/6546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media\/6547"}],"wp:attachment":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media?parent=6546"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_cat?post=6546"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_tag?post=6546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}