{"id":4655,"date":"2023-09-27T13:39:32","date_gmt":"2023-09-27T08:09:32","guid":{"rendered":"https:\/\/staging.analyticachemie.in\/?post_type=product&#038;p=4655"},"modified":"2023-11-03T18:01:42","modified_gmt":"2023-11-03T12:31:42","slug":"eicosatetraeoic-acid-ethyl-ester","status":"publish","type":"product","link":"https:\/\/analyticachemie.in\/ver-2\/product\/eicosatetraeoic-acid-ethyl-ester\/","title":{"rendered":"Eicosatetraeoic acid ethyl ester"},"content":{"rendered":"<p>ACI-R05009 1808-26-0 Eicosatetraeoic acid ethyl ester C22H36O2 5,8,11,14-Eicosatetraenoic acid ethyl ester<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACI-R05009 1808-26-0 Eicosatetraeoic acid ethyl ester C22H36O2 5,8,11,14-Eicosatetraenoic acid ethyl ester<\/p>\n","protected":false},"featured_media":4656,"template":"","meta":{"inline_featured_image":false},"product_cat":[88,18],"product_tag":[],"class_list":["post-4655","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-chemical-intermediate","product_cat-pharmaceutical-intermediates"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eicosatetraeoic acid ethyl ester - Analytica Chemie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eicosatetraeoic acid ethyl ester\" \/>\n<meta property=\"og:description\" content=\"ACI-R05009 1808-26-0 Eicosatetraeoic acid ethyl ester C22H36O2 5,8,11,14-Eicosatetraenoic acid ethyl ester\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/\" \/>\n<meta property=\"og:site_name\" content=\"Analytica Chemie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/analyticachemieinc\/yoast\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T12:31:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-R05009-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"158\" \/>\n\t<meta property=\"og:image:height\" content=\"114\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/eicosatetraeoic-acid-ethyl-ester\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/eicosatetraeoic-acid-ethyl-ester\\\/\",\"name\":\"Eicosatetraeoic acid ethyl ester - Analytica Chemie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/eicosatetraeoic-acid-ethyl-ester\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/eicosatetraeoic-acid-ethyl-ester\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-R05009-1.jpg\",\"datePublished\":\"2023-09-27T08:09:32+00:00\",\"dateModified\":\"2023-11-03T12:31:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/eicosatetraeoic-acid-ethyl-ester\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/analyticachemie.in\\\/product\\\/eicosatetraeoic-acid-ethyl-ester\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/eicosatetraeoic-acid-ethyl-ester\\\/#primaryimage\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-R05009-1.jpg\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-R05009-1.jpg\",\"width\":158,\"height\":114},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/eicosatetraeoic-acid-ethyl-ester\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eicosatetraeoic acid ethyl ester\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#website\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/\",\"name\":\"Analytica Chemie Inc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analyticachemie.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#organization\",\"name\":\"Analytica Chemie Inc\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"width\":3876,\"height\":1054,\"caption\":\"Analytica Chemie Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/analyticachemieinc\\\/yoast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/76600123\\\/admin\\\/dashboard\\\/yoast\",\"https:\\\/\\\/www.youtube.com\\\/@analyticachemieinc.6555\\\/yoast\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eicosatetraeoic acid ethyl ester - Analytica Chemie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/","og_locale":"en_US","og_type":"article","og_title":"Eicosatetraeoic acid ethyl ester","og_description":"ACI-R05009 1808-26-0 Eicosatetraeoic acid ethyl ester C22H36O2 5,8,11,14-Eicosatetraenoic acid ethyl ester","og_url":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/","og_site_name":"Analytica Chemie","article_publisher":"https:\/\/www.facebook.com\/analyticachemieinc\/yoast","article_modified_time":"2023-11-03T12:31:42+00:00","og_image":[{"width":158,"height":114,"url":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-R05009-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/","url":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/","name":"Eicosatetraeoic acid ethyl ester - Analytica Chemie","isPartOf":{"@id":"https:\/\/analyticachemie.in\/#website"},"primaryImageOfPage":{"@id":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/#primaryimage"},"image":{"@id":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/#primaryimage"},"thumbnailUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-R05009-1.jpg","datePublished":"2023-09-27T08:09:32+00:00","dateModified":"2023-11-03T12:31:42+00:00","breadcrumb":{"@id":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/#primaryimage","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-R05009-1.jpg","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-R05009-1.jpg","width":158,"height":114},{"@type":"BreadcrumbList","@id":"https:\/\/analyticachemie.in\/product\/eicosatetraeoic-acid-ethyl-ester\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analyticachemie.in\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/analyticachemie.in\/shop\/"},{"@type":"ListItem","position":3,"name":"Eicosatetraeoic acid ethyl ester"}]},{"@type":"WebSite","@id":"https:\/\/analyticachemie.in\/#website","url":"https:\/\/analyticachemie.in\/","name":"Analytica Chemie Inc","description":"","publisher":{"@id":"https:\/\/analyticachemie.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analyticachemie.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/analyticachemie.in\/#organization","name":"Analytica Chemie Inc","url":"https:\/\/analyticachemie.in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/#\/schema\/logo\/image\/","url":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-Logo.png","contentUrl":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-Logo.png","width":3876,"height":1054,"caption":"Analytica Chemie Inc"},"image":{"@id":"https:\/\/analyticachemie.in\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/analyticachemieinc\/yoast","https:\/\/www.linkedin.com\/company\/76600123\/admin\/dashboard\/yoast","https:\/\/www.youtube.com\/@analyticachemieinc.6555\/yoast"]}]}},"_links":{"self":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product\/4655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media\/4656"}],"wp:attachment":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media?parent=4655"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_cat?post=4655"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_tag?post=4655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}