{"id":4334,"date":"2023-09-27T13:37:37","date_gmt":"2023-09-27T08:07:37","guid":{"rendered":"https:\/\/staging.analyticachemie.in\/?post_type=product&#038;p=4334"},"modified":"2023-11-03T18:00:47","modified_gmt":"2023-11-03T12:30:47","slug":"diltiazem-hydrochloride-imp-f-ep-as-hydrochloride","status":"publish","type":"product","link":"https:\/\/analyticachemie.in\/ver-2\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/","title":{"rendered":"Diltiazem hydrochloride Imp. F  (EP) as hydrochloride"},"content":{"rendered":"<p>ACI-042806 23515-45-9 Diltiazem hydrochloride Imp. F  (EP) as hydrochloride C20H25ClN2O3S  (2S,3S)-5-[2-(dimethylamino)ethyl]-3-hydroxy-2-(4-methoxyphenyl)-2,3-dihydro-1,5-benzothiazepin-4(5H)-one hydrochloride<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACI-042806 23515-45-9 Diltiazem hydrochloride Imp. F (EP) as hydrochloride C20H25ClN2O3S (2S,3S)-5-[2-(dimethylamino)ethyl]-3-hydroxy-2-(4-methoxyphenyl)-2,3-dihydro-1,5-benzothiazepin-4(5H)-one hydrochloride<\/p>\n","protected":false},"featured_media":4335,"template":"","meta":{"inline_featured_image":false},"product_cat":[649,16],"product_tag":[],"class_list":["post-4334","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-diltiazem-pharmaceutical-impurity-standards","product_cat-pharmaceutical-impurity-standards"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Diltiazem hydrochloride Imp. F (EP) as hydrochloride - Analytica Chemie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diltiazem hydrochloride Imp. F (EP) as hydrochloride\" \/>\n<meta property=\"og:description\" content=\"ACI-042806 23515-45-9 Diltiazem hydrochloride Imp. F (EP) as hydrochloride C20H25ClN2O3S (2S,3S)-5-[2-(dimethylamino)ethyl]-3-hydroxy-2-(4-methoxyphenyl)-2,3-dihydro-1,5-benzothiazepin-4(5H)-one hydrochloride\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/\" \/>\n<meta property=\"og:site_name\" content=\"Analytica Chemie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/analyticachemieinc\/yoast\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T12:30:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-042806.png\" \/>\n\t<meta property=\"og:image:width\" content=\"293\" \/>\n\t<meta property=\"og:image:height\" content=\"152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\\\/\",\"name\":\"Diltiazem hydrochloride Imp. F (EP) as hydrochloride - Analytica Chemie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-042806.png\",\"datePublished\":\"2023-09-27T08:07:37+00:00\",\"dateModified\":\"2023-11-03T12:30:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/analyticachemie.in\\\/product\\\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\\\/#primaryimage\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-042806.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-042806.png\",\"width\":293,\"height\":152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diltiazem hydrochloride Imp. F (EP) as hydrochloride\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#website\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/\",\"name\":\"Analytica Chemie Inc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analyticachemie.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#organization\",\"name\":\"Analytica Chemie Inc\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"width\":3876,\"height\":1054,\"caption\":\"Analytica Chemie Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/analyticachemieinc\\\/yoast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/76600123\\\/admin\\\/dashboard\\\/yoast\",\"https:\\\/\\\/www.youtube.com\\\/@analyticachemieinc.6555\\\/yoast\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Diltiazem hydrochloride Imp. F (EP) as hydrochloride - Analytica Chemie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/","og_locale":"en_US","og_type":"article","og_title":"Diltiazem hydrochloride Imp. F (EP) as hydrochloride","og_description":"ACI-042806 23515-45-9 Diltiazem hydrochloride Imp. F (EP) as hydrochloride C20H25ClN2O3S (2S,3S)-5-[2-(dimethylamino)ethyl]-3-hydroxy-2-(4-methoxyphenyl)-2,3-dihydro-1,5-benzothiazepin-4(5H)-one hydrochloride","og_url":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/","og_site_name":"Analytica Chemie","article_publisher":"https:\/\/www.facebook.com\/analyticachemieinc\/yoast","article_modified_time":"2023-11-03T12:30:47+00:00","og_image":[{"width":293,"height":152,"url":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-042806.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/","url":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/","name":"Diltiazem hydrochloride Imp. F (EP) as hydrochloride - Analytica Chemie","isPartOf":{"@id":"https:\/\/analyticachemie.in\/#website"},"primaryImageOfPage":{"@id":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/#primaryimage"},"image":{"@id":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/#primaryimage"},"thumbnailUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-042806.png","datePublished":"2023-09-27T08:07:37+00:00","dateModified":"2023-11-03T12:30:47+00:00","breadcrumb":{"@id":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/#primaryimage","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-042806.png","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-042806.png","width":293,"height":152},{"@type":"BreadcrumbList","@id":"https:\/\/analyticachemie.in\/product\/diltiazem-hydrochloride-imp-f-ep-as-hydrochloride\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analyticachemie.in\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/analyticachemie.in\/shop\/"},{"@type":"ListItem","position":3,"name":"Diltiazem hydrochloride Imp. F (EP) as hydrochloride"}]},{"@type":"WebSite","@id":"https:\/\/analyticachemie.in\/#website","url":"https:\/\/analyticachemie.in\/","name":"Analytica Chemie Inc","description":"","publisher":{"@id":"https:\/\/analyticachemie.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analyticachemie.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/analyticachemie.in\/#organization","name":"Analytica Chemie Inc","url":"https:\/\/analyticachemie.in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/#\/schema\/logo\/image\/","url":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-Logo.png","contentUrl":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-Logo.png","width":3876,"height":1054,"caption":"Analytica Chemie Inc"},"image":{"@id":"https:\/\/analyticachemie.in\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/analyticachemieinc\/yoast","https:\/\/www.linkedin.com\/company\/76600123\/admin\/dashboard\/yoast","https:\/\/www.youtube.com\/@analyticachemieinc.6555\/yoast"]}]}},"_links":{"self":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product\/4334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media\/4335"}],"wp:attachment":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media?parent=4334"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_cat?post=4334"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_tag?post=4334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}