{"id":3746,"date":"2023-09-25T20:40:47","date_gmt":"2023-09-25T15:10:47","guid":{"rendered":"https:\/\/staging.analyticachemie.in\/?post_type=product&#038;p=3746"},"modified":"2026-03-07T14:01:11","modified_gmt":"2026-03-07T08:31:11","slug":"clothianidin-impurity-3","status":"publish","type":"product","link":"https:\/\/analyticachemie.in\/ver-2\/product\/clothianidin-impurity-3\/","title":{"rendered":"Clothianidin Impurity 3"},"content":{"rendered":"<p>ACI-036803 NA Clothianidin Impurity C6H7Cl2N5O2S N-(2,4-dichlrothiazol-5 ylmethyl) N`-methyl-N`-nitro guanidine<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACI-036803 NA Clothianidin Impurity C6H7Cl2N5O2S N-(2,4-dichlrothiazol-5 ylmethyl) N`-methyl-N`-nitro guanidine<\/p>\n","protected":false},"featured_media":14009,"template":"","meta":{"inline_featured_image":false},"product_cat":[540,16],"product_tag":[],"class_list":["post-3746","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-clothianidin","product_cat-pharmaceutical-impurity-standards"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Clothianidin Impurity 3 - Analytica Chemie<\/title>\n<meta name=\"description\" content=\"BUY Clothianidin Impurity 3 Mol formula C6H7Cl2N5O2S Mol wt 284.12\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clothianidin Impurity 3\" \/>\n<meta property=\"og:description\" content=\"BUY Clothianidin Impurity 3 Mol formula C6H7Cl2N5O2S Mol wt 284.12\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Analytica Chemie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/analyticachemieinc\/yoast\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-07T08:31:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-036803-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"544\" \/>\n\t<meta property=\"og:image:height\" content=\"242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/clothianidin-impurity-3\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/clothianidin-impurity-3\\\/\",\"name\":\"Clothianidin Impurity 3 - Analytica Chemie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/clothianidin-impurity-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/clothianidin-impurity-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-036803-1.png\",\"datePublished\":\"2023-09-25T15:10:47+00:00\",\"dateModified\":\"2026-03-07T08:31:11+00:00\",\"description\":\"BUY Clothianidin Impurity 3 Mol formula C6H7Cl2N5O2S Mol wt 284.12\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/clothianidin-impurity-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/analyticachemie.in\\\/product\\\/clothianidin-impurity-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/clothianidin-impurity-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-036803-1.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-036803-1.png\",\"width\":544,\"height\":242},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/clothianidin-impurity-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Clothianidin Impurity 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#website\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\",\"name\":\"Analytica Chemie Inc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#organization\",\"name\":\"Analytica Chemie Inc\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"width\":3876,\"height\":1054,\"caption\":\"Analytica Chemie Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/analyticachemieinc\\\/yoast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/76600123\\\/admin\\\/dashboard\\\/yoast\",\"https:\\\/\\\/www.youtube.com\\\/@analyticachemieinc.6555\\\/yoast\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Clothianidin Impurity 3 - Analytica Chemie","description":"BUY Clothianidin Impurity 3 Mol formula C6H7Cl2N5O2S Mol wt 284.12","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/","og_locale":"en_US","og_type":"article","og_title":"Clothianidin Impurity 3","og_description":"BUY Clothianidin Impurity 3 Mol formula C6H7Cl2N5O2S Mol wt 284.12","og_url":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/","og_site_name":"Analytica Chemie","article_publisher":"https:\/\/www.facebook.com\/analyticachemieinc\/yoast","article_modified_time":"2026-03-07T08:31:11+00:00","og_image":[{"width":544,"height":242,"url":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-036803-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/","url":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/","name":"Clothianidin Impurity 3 - Analytica Chemie","isPartOf":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/#primaryimage"},"image":{"@id":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/#primaryimage"},"thumbnailUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-036803-1.png","datePublished":"2023-09-25T15:10:47+00:00","dateModified":"2026-03-07T08:31:11+00:00","description":"BUY Clothianidin Impurity 3 Mol formula C6H7Cl2N5O2S Mol wt 284.12","breadcrumb":{"@id":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/#primaryimage","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-036803-1.png","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-036803-1.png","width":544,"height":242},{"@type":"BreadcrumbList","@id":"https:\/\/analyticachemie.in\/product\/clothianidin-impurity-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analyticachemie.in\/ver-2\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/analyticachemie.in\/ver-2\/shop\/"},{"@type":"ListItem","position":3,"name":"Clothianidin Impurity 3"}]},{"@type":"WebSite","@id":"https:\/\/analyticachemie.in\/ver-2\/#website","url":"https:\/\/analyticachemie.in\/ver-2\/","name":"Analytica Chemie Inc","description":"","publisher":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analyticachemie.in\/ver-2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/analyticachemie.in\/ver-2\/#organization","name":"Analytica Chemie Inc","url":"https:\/\/analyticachemie.in\/ver-2\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/ver-2\/#\/schema\/logo\/image\/","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-Logo.png","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-Logo.png","width":3876,"height":1054,"caption":"Analytica Chemie Inc"},"image":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/analyticachemieinc\/yoast","https:\/\/www.linkedin.com\/company\/76600123\/admin\/dashboard\/yoast","https:\/\/www.youtube.com\/@analyticachemieinc.6555\/yoast"]}]}},"_links":{"self":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product\/3746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media\/14009"}],"wp:attachment":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media?parent=3746"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_cat?post=3746"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_tag?post=3746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}