{"id":3132,"date":"2023-09-25T20:37:07","date_gmt":"2023-09-25T15:07:07","guid":{"rendered":"https:\/\/staging.analyticachemie.in\/?post_type=product&#038;p=3132"},"modified":"2023-11-03T17:57:51","modified_gmt":"2023-11-03T12:27:51","slug":"calcium-23-dihydroxypropyl-phosphate-hydrate","status":"publish","type":"product","link":"https:\/\/analyticachemie.in\/ver-2\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/","title":{"rendered":"Calcium 2,3-dihydroxypropyl phosphate Hydrate"},"content":{"rendered":"<p>ACI-R03033 27214-00-2 Calcium 2,3-dihydroxypropyl phosphate Hydrate C3H7CaO6P.xH2O Calcium Glycerophosphate Hydrate<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACI-R03033 27214-00-2 Calcium 2,3-dihydroxypropyl phosphate Hydrate C3H7CaO6P.xH2O Calcium Glycerophosphate Hydrate<\/p>\n","protected":false},"featured_media":3133,"template":"","meta":{"inline_featured_image":false},"product_cat":[88,18],"product_tag":[],"class_list":["post-3132","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-chemical-intermediate","product_cat-pharmaceutical-intermediates"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Calcium 2,3-dihydroxypropyl phosphate Hydrate - Analytica Chemie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calcium 2,3-dihydroxypropyl phosphate Hydrate\" \/>\n<meta property=\"og:description\" content=\"ACI-R03033 27214-00-2 Calcium 2,3-dihydroxypropyl phosphate Hydrate C3H7CaO6P.xH2O Calcium Glycerophosphate Hydrate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/\" \/>\n<meta property=\"og:site_name\" content=\"Analytica Chemie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/analyticachemieinc\/yoast\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T12:27:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-R03033-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"391\" \/>\n\t<meta property=\"og:image:height\" content=\"331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/calcium-23-dihydroxypropyl-phosphate-hydrate\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/calcium-23-dihydroxypropyl-phosphate-hydrate\\\/\",\"name\":\"Calcium 2,3-dihydroxypropyl phosphate Hydrate - Analytica Chemie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/calcium-23-dihydroxypropyl-phosphate-hydrate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/calcium-23-dihydroxypropyl-phosphate-hydrate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-R03033-1.jpg\",\"datePublished\":\"2023-09-25T15:07:07+00:00\",\"dateModified\":\"2023-11-03T12:27:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/calcium-23-dihydroxypropyl-phosphate-hydrate\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/analyticachemie.in\\\/product\\\/calcium-23-dihydroxypropyl-phosphate-hydrate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/calcium-23-dihydroxypropyl-phosphate-hydrate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-R03033-1.jpg\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-R03033-1.jpg\",\"width\":391,\"height\":331},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/product\\\/calcium-23-dihydroxypropyl-phosphate-hydrate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Calcium 2,3-dihydroxypropyl phosphate Hydrate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#website\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\",\"name\":\"Analytica Chemie Inc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#organization\",\"name\":\"Analytica Chemie Inc\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"width\":3876,\"height\":1054,\"caption\":\"Analytica Chemie Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/analyticachemieinc\\\/yoast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/76600123\\\/admin\\\/dashboard\\\/yoast\",\"https:\\\/\\\/www.youtube.com\\\/@analyticachemieinc.6555\\\/yoast\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Calcium 2,3-dihydroxypropyl phosphate Hydrate - Analytica Chemie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/","og_locale":"en_US","og_type":"article","og_title":"Calcium 2,3-dihydroxypropyl phosphate Hydrate","og_description":"ACI-R03033 27214-00-2 Calcium 2,3-dihydroxypropyl phosphate Hydrate C3H7CaO6P.xH2O Calcium Glycerophosphate Hydrate","og_url":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/","og_site_name":"Analytica Chemie","article_publisher":"https:\/\/www.facebook.com\/analyticachemieinc\/yoast","article_modified_time":"2023-11-03T12:27:51+00:00","og_image":[{"width":391,"height":331,"url":"https:\/\/analyticachemie.in\/wp-content\/uploads\/ACI-R03033-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/","url":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/","name":"Calcium 2,3-dihydroxypropyl phosphate Hydrate - Analytica Chemie","isPartOf":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/#primaryimage"},"image":{"@id":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/#primaryimage"},"thumbnailUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-R03033-1.jpg","datePublished":"2023-09-25T15:07:07+00:00","dateModified":"2023-11-03T12:27:51+00:00","breadcrumb":{"@id":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/#primaryimage","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-R03033-1.jpg","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-R03033-1.jpg","width":391,"height":331},{"@type":"BreadcrumbList","@id":"https:\/\/analyticachemie.in\/product\/calcium-23-dihydroxypropyl-phosphate-hydrate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analyticachemie.in\/ver-2\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/analyticachemie.in\/ver-2\/shop\/"},{"@type":"ListItem","position":3,"name":"Calcium 2,3-dihydroxypropyl phosphate Hydrate"}]},{"@type":"WebSite","@id":"https:\/\/analyticachemie.in\/ver-2\/#website","url":"https:\/\/analyticachemie.in\/ver-2\/","name":"Analytica Chemie Inc","description":"","publisher":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analyticachemie.in\/ver-2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/analyticachemie.in\/ver-2\/#organization","name":"Analytica Chemie Inc","url":"https:\/\/analyticachemie.in\/ver-2\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/ver-2\/#\/schema\/logo\/image\/","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-Logo.png","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-Logo.png","width":3876,"height":1054,"caption":"Analytica Chemie Inc"},"image":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/analyticachemieinc\/yoast","https:\/\/www.linkedin.com\/company\/76600123\/admin\/dashboard\/yoast","https:\/\/www.youtube.com\/@analyticachemieinc.6555\/yoast"]}]}},"_links":{"self":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product\/3132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media\/3133"}],"wp:attachment":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media?parent=3132"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_cat?post=3132"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_tag?post=3132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}