{"id":2736,"date":"2023-09-25T20:34:41","date_gmt":"2023-09-25T15:04:41","guid":{"rendered":"https:\/\/staging.analyticachemie.in\/?post_type=product&#038;p=2736"},"modified":"2023-11-03T17:56:44","modified_gmt":"2023-11-03T12:26:44","slug":"benzoyl-peroxide-hydrous","status":"publish","type":"product","link":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/","title":{"rendered":"Benzoyl peroxide, hydrous"},"content":{"rendered":"<p>ACI-023600 94-36-0 Benzoyl peroxide, hydrous  C14H10O4 Anhydrous benzol peroxide<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACI-023600 94-36-0 Benzoyl peroxide, hydrous C14H10O4 Anhydrous benzol peroxide<\/p>\n","protected":false},"featured_media":2737,"template":"","meta":{"inline_featured_image":false},"product_cat":[340,18],"product_tag":[],"class_list":["post-2736","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-benzoyl-peroxide-hydrous","product_cat-pharmaceutical-intermediates"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Benzoyl peroxide, hydrous - Analytica Chemie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benzoyl peroxide, hydrous\" \/>\n<meta property=\"og:description\" content=\"ACI-023600 94-36-0 Benzoyl peroxide, hydrous C14H10O4 Anhydrous benzol peroxide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/\" \/>\n<meta property=\"og:site_name\" content=\"Analytica Chemie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/analyticachemieinc\/yoast\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T12:26:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-023600-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"257\" \/>\n\t<meta property=\"og:image:height\" content=\"122\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/benzoyl-peroxide-hydrous\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/benzoyl-peroxide-hydrous\\\/\",\"name\":\"Benzoyl peroxide, hydrous - Analytica Chemie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/benzoyl-peroxide-hydrous\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/benzoyl-peroxide-hydrous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-023600-1.jpg\",\"datePublished\":\"2023-09-25T15:04:41+00:00\",\"dateModified\":\"2023-11-03T12:26:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/benzoyl-peroxide-hydrous\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/benzoyl-peroxide-hydrous\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/benzoyl-peroxide-hydrous\\\/#primaryimage\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-023600-1.jpg\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-023600-1.jpg\",\"width\":257,\"height\":122},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/product\\\/benzoyl-peroxide-hydrous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Benzoyl peroxide, hydrous\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#website\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\",\"name\":\"Analytica Chemie Inc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#organization\",\"name\":\"Analytica Chemie Inc\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"contentUrl\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/wp-content\\\/uploads\\\/ACI-Logo.png\",\"width\":3876,\"height\":1054,\"caption\":\"Analytica Chemie Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/analyticachemie.in\\\/ver-2\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/analyticachemieinc\\\/yoast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/76600123\\\/admin\\\/dashboard\\\/yoast\",\"https:\\\/\\\/www.youtube.com\\\/@analyticachemieinc.6555\\\/yoast\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Benzoyl peroxide, hydrous - Analytica Chemie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/","og_locale":"en_US","og_type":"article","og_title":"Benzoyl peroxide, hydrous","og_description":"ACI-023600 94-36-0 Benzoyl peroxide, hydrous C14H10O4 Anhydrous benzol peroxide","og_url":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/","og_site_name":"Analytica Chemie","article_publisher":"https:\/\/www.facebook.com\/analyticachemieinc\/yoast","article_modified_time":"2023-11-03T12:26:44+00:00","og_image":[{"width":257,"height":122,"url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-023600-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/","url":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/","name":"Benzoyl peroxide, hydrous - Analytica Chemie","isPartOf":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/#primaryimage"},"image":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/#primaryimage"},"thumbnailUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-023600-1.jpg","datePublished":"2023-09-25T15:04:41+00:00","dateModified":"2023-11-03T12:26:44+00:00","breadcrumb":{"@id":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/#primaryimage","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-023600-1.jpg","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-023600-1.jpg","width":257,"height":122},{"@type":"BreadcrumbList","@id":"https:\/\/analyticachemie.in\/ver-2\/product\/benzoyl-peroxide-hydrous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analyticachemie.in\/ver-2\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/analyticachemie.in\/ver-2\/shop\/"},{"@type":"ListItem","position":3,"name":"Benzoyl peroxide, hydrous"}]},{"@type":"WebSite","@id":"https:\/\/analyticachemie.in\/ver-2\/#website","url":"https:\/\/analyticachemie.in\/ver-2\/","name":"Analytica Chemie Inc","description":"","publisher":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analyticachemie.in\/ver-2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/analyticachemie.in\/ver-2\/#organization","name":"Analytica Chemie Inc","url":"https:\/\/analyticachemie.in\/ver-2\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/analyticachemie.in\/ver-2\/#\/schema\/logo\/image\/","url":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-Logo.png","contentUrl":"https:\/\/analyticachemie.in\/ver-2\/wp-content\/uploads\/ACI-Logo.png","width":3876,"height":1054,"caption":"Analytica Chemie Inc"},"image":{"@id":"https:\/\/analyticachemie.in\/ver-2\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/analyticachemieinc\/yoast","https:\/\/www.linkedin.com\/company\/76600123\/admin\/dashboard\/yoast","https:\/\/www.youtube.com\/@analyticachemieinc.6555\/yoast"]}]}},"_links":{"self":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product\/2736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media\/2737"}],"wp:attachment":[{"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/media?parent=2736"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_cat?post=2736"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/analyticachemie.in\/ver-2\/wp-json\/wp\/v2\/product_tag?post=2736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}